{"id":1016,"date":"2022-02-28T17:29:44","date_gmt":"2022-02-28T16:29:44","guid":{"rendered":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg"},"modified":"2022-02-28T17:29:44","modified_gmt":"2022-02-28T16:29:44","slug":"boutique-hotel-de-france-2","status":"inherit","type":"attachment","link":"https:\/\/www.hdefrance.com\/en\/accueil\/boutique-hotel-de-france-2\/","title":{"rendered":"boutique hotel de france"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-1016","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>boutique hotel de france - H\u00f4tel de France<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"boutique hotel de france - H\u00f4tel de France\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg\" \/>\n<meta property=\"og:site_name\" content=\"H\u00f4tel de France\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"711\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hdefrance.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/boutique-hotel-de-france.jpg\",\"url\":\"https:\\\/\\\/www.hdefrance.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/boutique-hotel-de-france.jpg\",\"name\":\"boutique hotel de france - H\u00f4tel de France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hdefrance.com\\\/#website\"},\"datePublished\":\"2022-02-28T16:29:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hdefrance.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/boutique-hotel-de-france.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hdefrance.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/boutique-hotel-de-france.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hdefrance.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/boutique-hotel-de-france.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hdefrance.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hdefrance.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"boutique hotel de france\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hdefrance.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hdefrance.com\\\/\",\"name\":\"H\u00f4tel de France\",\"description\":\"H\u00f4tel Restaurant \u00e0 Castelnaudary\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hdefrance.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"boutique hotel de france - H\u00f4tel de France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg","og_locale":"en_US","og_type":"article","og_title":"boutique hotel de france - H\u00f4tel de France","og_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg","og_site_name":"H\u00f4tel de France","og_image":[{"width":711,"height":533,"url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg","url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg","name":"boutique hotel de france - H\u00f4tel de France","isPartOf":{"@id":"https:\/\/www.hdefrance.com\/#website"},"datePublished":"2022-02-28T16:29:44+00:00","breadcrumb":{"@id":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hdefrance.com\/en\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.hdefrance.com\/en\/"},{"@type":"ListItem","position":3,"name":"boutique hotel de france"}]},{"@type":"WebSite","@id":"https:\/\/www.hdefrance.com\/#website","url":"https:\/\/www.hdefrance.com\/","name":"H\u00f4tel de France","description":"H\u00f4tel Restaurant \u00e0 Castelnaudary","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hdefrance.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-300x225.jpg 300w, https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-558x418.jpg 558w, https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-655x491.jpg 655w, https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-600x450.jpg 600w, https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg 711w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":711,"height":533,"file":"2022\/02\/boutique-hotel-de-france.jpg","sizes":{"medium":{"file":"boutique-hotel-de-france-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-300x225.jpg"},"thumbnail":{"file":"boutique-hotel-de-france-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-150x150.jpg"},"blog-thumb-1":{"file":"boutique-hotel-de-france-468x328.jpg","width":468,"height":328,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-468x328.jpg"},"blog-thumb-2":{"file":"boutique-hotel-de-france-468x468.jpg","width":468,"height":468,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-468x468.jpg"},"portfolio-single-img-4":{"file":"boutique-hotel-de-france-558x418.jpg","width":558,"height":418,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-558x418.jpg"},"portfolio-img-1":{"file":"boutique-hotel-de-france-360x300.jpg","width":360,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-360x300.jpg"},"portfolio-img-2":{"file":"boutique-hotel-de-france-655x533.jpg","width":655,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-655x533.jpg"},"portfolio-img-3":{"file":"boutique-hotel-de-france-655x491.jpg","width":655,"height":491,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-655x491.jpg"},"shop-category-thumb":{"file":"boutique-hotel-de-france-500x290.jpg","width":500,"height":290,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-500x290.jpg"},"woocommerce_thumbnail":{"file":"boutique-hotel-de-france-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-300x300.jpg"},"woocommerce_single":{"file":"boutique-hotel-de-france-600x450.jpg","width":600,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-600x450.jpg"},"woocommerce_gallery_thumbnail":{"file":"boutique-hotel-de-france-220x220.jpg","width":220,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-220x220.jpg"},"shop_catalog":{"file":"boutique-hotel-de-france-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-300x300.jpg"},"shop_single":{"file":"boutique-hotel-de-france-600x450.jpg","width":600,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-600x450.jpg"},"shop_thumbnail":{"file":"boutique-hotel-de-france-220x220.jpg","width":220,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france-220x220.jpg"},"full":{"file":"boutique-hotel-de-france.jpg","width":711,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg"}},"image_meta":{"aperture":"1.89","credit":"","camera":"M2101K6G","caption":"","created_timestamp":"1643298054","copyright":"","focal_length":"5.89","iso":"50","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]}},"post":379,"source_url":"https:\/\/www.hdefrance.com\/wp-content\/uploads\/2022\/02\/boutique-hotel-de-france.jpg","filename":"boutique-hotel-de-france.jpg","filesize":449860,"_links":{"self":[{"href":"https:\/\/www.hdefrance.com\/en\/wp-json\/wp\/v2\/media\/1016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hdefrance.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.hdefrance.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.hdefrance.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hdefrance.com\/en\/wp-json\/wp\/v2\/comments?post=1016"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":379,"href":"https:\/\/www.hdefrance.com\/en\/wp-json\/wp\/v2\/pages\/379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}